{"id":5665,"date":"2026-07-12T19:58:55","date_gmt":"2026-07-12T17:58:55","guid":{"rendered":"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/"},"modified":"2026-07-12T19:58:58","modified_gmt":"2026-07-12T17:58:58","slug":"je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant","status":"publish","type":"post","link":"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/","title":{"rendered":"Je suis entr\u00e9 dans une immense foule norv\u00e9gienne avec mon maillot anglais \u2013 ce qui s&#39;est pass\u00e9 ensuite a \u00e9t\u00e9 choquant."},"content":{"rendered":"<div>\n<p>Les supporters norv\u00e9giens seraient peut-\u00eatre devenus c\u00e9l\u00e8bres lors de la Coupe du monde 2026 pour leur combat contre les Vikings. Mais contrairement \u00e0 leurs anc\u00eatres, les battements de tambour et les cris scandinaves ne sont heureusement pas suivis de raids sauvages contre les habitants locaux sans m\u00e9fiance.<\/p>\n<p>Mais je voulais voir si la bonne humeur norv\u00e9gienne serait toujours intacte face \u00e0 un supporter anglais exhibant le troph\u00e9e de la Coupe du monde avant le quart de finale crucial entre les deux \u00e9quipes.<\/p>\n<p>Cette fameuse politesse scandinave perdurerait-elle, ou attiserait-elle l&#39;ancien esprit viking qui les rendait si redout\u00e9s dans les \u00eeles britanniques il y a plusieurs si\u00e8cles ?<\/p>\n<p>Malgr\u00e9 toutes les discussions sur les 30 000 supporters anglais envahissant Miami avant les quarts de finale de la Coupe du monde, la bande de bars et de restaurants Ocean View o\u00f9 les fans de football se sont rassembl\u00e9s avant les matchs \u00e9tait une mer de rouge.<\/p>\n<p>La Norv\u00e8ge n&#39;a peut-\u00eatre qu&#39;une population l\u00e9g\u00e8rement plus nombreuse que l&#39;\u00c9cosse, mais, tout comme l&#39;arm\u00e9e tartan, priv\u00e9e de tournoi majeur depuis des d\u00e9cennies, elle s&#39;est rendue en masse aux \u00c9tats-Unis.<\/p>\n<p>En fait, la foule qui effectuait le d\u00e9fil\u00e9 des Vikings \u00e9tait si nombreuse qu&#39;elle a d\u00fb \u00eatre dispers\u00e9e \u00e0 deux reprises par la police locale \u00e0 bord de buggys.<\/p>\n<p>La question que je me posais \u00e9tait de savoir ce que le public norv\u00e9gien penserait d&#39;un Anglais solitaire portant la Coupe du Monde sur les \u00e9paules d&#39;un ami, \u00e0 la mani\u00e8re de Bobby Moore.<\/p>\n<\/div>\n<div>\n<p>Il est juste de dire que les supporters norv\u00e9giens \u00e9taient plut\u00f4t bien huil\u00e9s au moment o\u00f9 nous sommes entr\u00e9s dans le ventre de la b\u00eate.<\/p>\n<p>Alors que nous nous dirigions vers le groupe le plus nombreux, nous avons vu un agent de s\u00e9curit\u00e9 expulser un supporter norv\u00e9gien v\u00eatu d&#39;une chemise d&#39;Erling Haaland, qui narguait un groupe d&#39;Anglais en chantant \u00ab L&#39;Angleterre rentre chez elle \u00bb. Plus loin sur le Strip, un supporter se d\u00e9hanchant v\u00eatu d&#39;un maillot r\u00e9tro des ann\u00e9es 90 faisait des gestes grossiers envers un robot dansant amen\u00e9 sur la plage par une \u00e9quipe de t\u00e9l\u00e9vision \u00e9trang\u00e8re.<\/p>\n<p>J&#39;ai donc enfil\u00e9 mon maillot des Trois Lions et je l&#39;ai mis \u00e0 l&#39;\u00e9preuve, en traversant un trottoir rempli de Norv\u00e9giens sur les \u00e9paules d&#39;un courageux supporter.<\/p>\n<p>Le d\u00e9but a \u00e9t\u00e9 un peu chaotique car, apr\u00e8s avoir \u00e9t\u00e9 soulev\u00e9s dans les airs, nous avons failli nous \u00e9craser contre un parapluie. Mais apr\u00e8s nous \u00eatre stabilis\u00e9s, nous nous sommes int\u00e9gr\u00e9s \u00e0 la foule et avons soulev\u00e9 le troph\u00e9e.<\/p>\n<p>Les Norv\u00e9giens ont r\u00e9agi par des rires, des hu\u00e9es et une quantit\u00e9 \u00e9tonnamment \u00e9lev\u00e9e de jurons, \u00e0 la fois sonores et visuelles. Bient\u00f4t, nous f\u00fbmes compl\u00e8tement entour\u00e9s de Scandinaves hurlant leur chant anti-Angleterre pr\u00e9f\u00e9r\u00e9, \u00ab England&#39;s go home \u00bb, sur l&#39;air de Three Lions (Football&#39;s Coming Home).<\/p>\n<p>J&#39;ai fait de mon mieux pour leur chanter la bonne version, et pendant quelques bonnes minutes, nous sommes rest\u00e9s enferm\u00e9s dans cette \u00e9trange chanson. Nous chantons tous les deux le m\u00eame air avec des paroles presque identiques, mais surtout pas identiques.<\/p>\n<p>La sc\u00e8ne a rapidement attir\u00e9 l&#39;attention de plusieurs \u00e9quipes de t\u00e9l\u00e9vision qui filmaient les supporters norv\u00e9giens et, bizarrement, un journaliste d&#39;une cha\u00eene hispanophone a tent\u00e9 de m&#39;interviewer alors que j&#39;\u00e9tais au milieu de la foule.<\/p>\n<p>Je n&#39;entendais pas un mot de ce qu&#39;il disait \u00e0 cause du bruit, alors quand il m&#39;a point\u00e9 son micro bleu au visage, j&#39;ai esp\u00e9r\u00e9 qu&#39;une autre interpr\u00e9tation de Football&#39;s Coming Home serait la phrase sonore dont il avait besoin.<\/p>\n<p>En regardant de l&#39;autre c\u00f4t\u00e9, j&#39;ai pu constater que, inexplicablement, le robot avait \u00e9galement \u00e9t\u00e9 introduit dans la foule des Norv\u00e9giens et avait du mal \u00e0 se d\u00e9placer entre deux gros fans portant des chapeaux de Viking.<\/p>\n<p>\u00c0 ce stade, le DJ du bar devant lequel nous passions avait eu vent de notre cascade et diffusait Football&#39;s Coming Home depuis ses haut-parleurs.<\/p>\n<p>\u00ab\u00a0G\u00e9nial\u00a0\u00bb, ai-je pens\u00e9, \u00ab\u00a0maintenant, je n&#39;ai plus besoin de rivaliser avec tous ces fans norv\u00e9giens parce qu&#39;ils jouent ma version\u00a0\u00bb.<\/p>\n<p>Mais le DJ \u00e9tait plus malin que \u00e7a. Alors que la chanson atteignait un crescendo, il a coup\u00e9 la musique et a demand\u00e9 \u00e0 la foule de fans en chemise rouge de se moquer de moi avec leur chanson \u00ab England&#39;s Going Home \u00bb.<\/p>\n<p>Apr\u00e8s cela, il y a eu un petit changement d\u2019ambiance. Un Norv\u00e9gien incroyablement ivre s\u2019est approch\u00e9 du courageux fan qui me transportait \u00e0 travers la foule et lui a dit : \u00ab Tu dois partir tout de suite. \u00bb La r\u00e9ponse de mon ami \u00ab\u00a0Tout va bien\u00a0\u00bb l&#39;a mis en col\u00e8re et il a commenc\u00e9 \u00e0 pousser mon compagnon dans la poitrine.<\/p>\n<p>Au m\u00eame moment, un autre homme blond tr\u00e8s ivre a commenc\u00e9 \u00e0 essayer de m&#39;arracher le troph\u00e9e de la Coupe du Monde et de me tirer les bras.<\/p>\n<p>Il \u00e9tait temps de sortir, alors nous nous sommes dirig\u00e9s vers un palmier voisin sur lequel nous appuyer pendant que je tombais au sol.<\/p>\n<p>Ce que je n&#39;avais pas r\u00e9alis\u00e9, c&#39;est que nous avions \u00e9t\u00e9 suivis par un supporter norv\u00e9gien d\u00e9termin\u00e9 \u00e0 voler le troph\u00e9e de la Coupe du monde.<\/p>\n<p>Alors que mes pieds touchaient le sol, il l&#39;a attrap\u00e9 et j&#39;ai d\u00fb le repousser alors qu&#39;il lan\u00e7ait ce que je ne peux que supposer \u00eatre un cri de guerre viking.<\/p>\n<p>Heureusement, j\u2019ai r\u00e9ussi \u00e0 r\u00e9cup\u00e9rer le troph\u00e9e et nous sommes partis pr\u00e9cipitamment.<\/p>\n<p>La le\u00e7on de l\u2019histoire est que, m\u00eame si la grande majorit\u00e9 des fans norv\u00e9giens ne sont que des Vikings pour plaisanter, il existe encore un couple pour qui la fougue de leurs anc\u00eatres fait surface apr\u00e8s une bi\u00e8re de trop.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les supporters norv\u00e9giens seraient peut-\u00eatre devenus c\u00e9l\u00e8bres lors de la Coupe du monde 2026 pour leur combat contre les Vikings. Mais contrairement \u00e0 leurs anc\u00eatres,<\/p>\n","protected":false},"author":1,"featured_media":5666,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2277],"tags":[4559,66,4777,54,6529,201,185,1739,1056,6527,4791,277,674,104,1325,1972,18],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Je suis entr\u00e9 dans une immense foule norv\u00e9gienne avec mon maillot anglais \u2013 ce qui s&#039;est pass\u00e9 ensuite a \u00e9t\u00e9 choquant.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Je suis entr\u00e9 dans une immense foule norv\u00e9gienne avec mon maillot anglais \u2013 ce qui s&#039;est pass\u00e9 ensuite a \u00e9t\u00e9 choquant.\" \/>\n<meta property=\"og:description\" content=\"Les supporters norv\u00e9giens seraient peut-\u00eatre devenus c\u00e9l\u00e8bres lors de la Coupe du monde 2026 pour leur combat contre les Vikings. Mais contrairement \u00e0 leurs anc\u00eatres,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/\" \/>\n<meta property=\"og:site_name\" content=\"www.Svalbard.fr\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-12T17:58:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-12T17:58:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.svalbard.fr\/actualites\/wp-content\/uploads\/2026\/07\/Je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hilmar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hilmar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/\"},\"author\":{\"name\":\"Hilmar\",\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/#\/schema\/person\/a2f937d5712222366738fae98755c600\"},\"headline\":\"Je suis entr\u00e9 dans une immense foule norv\u00e9gienne avec mon maillot anglais \u2013 ce qui s&#39;est pass\u00e9 ensuite a \u00e9t\u00e9 choquant.\",\"datePublished\":\"2026-07-12T17:58:55+00:00\",\"dateModified\":\"2026-07-12T17:58:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/\"},\"wordCount\":1060,\"publisher\":{\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/#organization\"},\"keywords\":[\"anglais\",\"avec\",\"choquant\",\"dans\",\"ensuite\",\"entre\",\"\u00e9t\u00e9\",\"foule\",\"Immense\",\"maillot\",\"Mon\",\"norv\u00e9gienne\",\"pass\u00e9\",\"qui\",\"s39est\",\"suis\",\"Une\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/\",\"url\":\"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/\",\"name\":\"Je suis entr\u00e9 dans une immense foule norv\u00e9gienne avec mon maillot anglais \u2013 ce qui s&#39;est pass\u00e9 ensuite a \u00e9t\u00e9 choquant.\",\"isPartOf\":{\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/#website\"},\"datePublished\":\"2026-07-12T17:58:55+00:00\",\"dateModified\":\"2026-07-12T17:58:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.svalbard.fr\/actualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Je suis entr\u00e9 dans une immense foule norv\u00e9gienne avec mon maillot anglais \u2013 ce qui s&#39;est pass\u00e9 ensuite a \u00e9t\u00e9 choquant.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/#website\",\"url\":\"https:\/\/www.svalbard.fr\/actualites\/\",\"name\":\"www.Svalbard.fr\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.svalbard.fr\/actualites\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/#organization\",\"name\":\"www.Svalbard.fr\",\"url\":\"https:\/\/www.svalbard.fr\/actualites\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.svalbard.fr\/actualites\/wp-content\/uploads\/2023\/09\/head-nom.jpg\",\"contentUrl\":\"https:\/\/www.svalbard.fr\/actualites\/wp-content\/uploads\/2023\/09\/head-nom.jpg\",\"width\":264,\"height\":35,\"caption\":\"www.Svalbard.fr\"},\"image\":{\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/#\/schema\/person\/a2f937d5712222366738fae98755c600\",\"name\":\"Hilmar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.svalbard.fr\/actualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4daa437093476dbc32da415c112b6512?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4daa437093476dbc32da415c112b6512?s=96&d=mm&r=g\",\"caption\":\"Hilmar\"},\"description\":\"Hilmar est un passionn\u00e9 des r\u00e9gions polaires, sp\u00e9cialis\u00e9 dans la r\u00e9daction d'articles sur le Spitzberg et autres destinations arctiques. Il apporte son expertise et sa passion pour l'Arctique au sein de l'\u00e9quipe de r\u00e9daction de Svalbard depuis de nombreuses ann\u00e9es.\",\"sameAs\":[\"https:\/\/www.svalbard.fr\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Je suis entr\u00e9 dans une immense foule norv\u00e9gienne avec mon maillot anglais \u2013 ce qui s&#39;est pass\u00e9 ensuite a \u00e9t\u00e9 choquant.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/","og_locale":"fr_FR","og_type":"article","og_title":"Je suis entr\u00e9 dans une immense foule norv\u00e9gienne avec mon maillot anglais \u2013 ce qui s&#39;est pass\u00e9 ensuite a \u00e9t\u00e9 choquant.","og_description":"Les supporters norv\u00e9giens seraient peut-\u00eatre devenus c\u00e9l\u00e8bres lors de la Coupe du monde 2026 pour leur combat contre les Vikings. Mais contrairement \u00e0 leurs anc\u00eatres,","og_url":"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/","og_site_name":"www.Svalbard.fr","article_published_time":"2026-07-12T17:58:55+00:00","article_modified_time":"2026-07-12T17:58:58+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.svalbard.fr\/actualites\/wp-content\/uploads\/2026\/07\/Je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon.jpg","type":"image\/jpeg"}],"author":"Hilmar","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Hilmar","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/#article","isPartOf":{"@id":"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/"},"author":{"name":"Hilmar","@id":"https:\/\/www.svalbard.fr\/actualites\/#\/schema\/person\/a2f937d5712222366738fae98755c600"},"headline":"Je suis entr\u00e9 dans une immense foule norv\u00e9gienne avec mon maillot anglais \u2013 ce qui s&#39;est pass\u00e9 ensuite a \u00e9t\u00e9 choquant.","datePublished":"2026-07-12T17:58:55+00:00","dateModified":"2026-07-12T17:58:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/"},"wordCount":1060,"publisher":{"@id":"https:\/\/www.svalbard.fr\/actualites\/#organization"},"keywords":["anglais","avec","choquant","dans","ensuite","entre","\u00e9t\u00e9","foule","Immense","maillot","Mon","norv\u00e9gienne","pass\u00e9","qui","s39est","suis","Une"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/","url":"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/","name":"Je suis entr\u00e9 dans une immense foule norv\u00e9gienne avec mon maillot anglais \u2013 ce qui s&#39;est pass\u00e9 ensuite a \u00e9t\u00e9 choquant.","isPartOf":{"@id":"https:\/\/www.svalbard.fr\/actualites\/#website"},"datePublished":"2026-07-12T17:58:55+00:00","dateModified":"2026-07-12T17:58:58+00:00","breadcrumb":{"@id":"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.svalbard.fr\/actualites\/je-suis-entre-dans-une-immense-foule-norvegienne-avec-mon-maillot-anglais-ce-qui-sest-passe-ensuite-a-ete-choquant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.svalbard.fr\/actualites\/"},{"@type":"ListItem","position":2,"name":"Je suis entr\u00e9 dans une immense foule norv\u00e9gienne avec mon maillot anglais \u2013 ce qui s&#39;est pass\u00e9 ensuite a \u00e9t\u00e9 choquant."}]},{"@type":"WebSite","@id":"https:\/\/www.svalbard.fr\/actualites\/#website","url":"https:\/\/www.svalbard.fr\/actualites\/","name":"www.Svalbard.fr","description":"","publisher":{"@id":"https:\/\/www.svalbard.fr\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.svalbard.fr\/actualites\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.svalbard.fr\/actualites\/#organization","name":"www.Svalbard.fr","url":"https:\/\/www.svalbard.fr\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.svalbard.fr\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/www.svalbard.fr\/actualites\/wp-content\/uploads\/2023\/09\/head-nom.jpg","contentUrl":"https:\/\/www.svalbard.fr\/actualites\/wp-content\/uploads\/2023\/09\/head-nom.jpg","width":264,"height":35,"caption":"www.Svalbard.fr"},"image":{"@id":"https:\/\/www.svalbard.fr\/actualites\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.svalbard.fr\/actualites\/#\/schema\/person\/a2f937d5712222366738fae98755c600","name":"Hilmar","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.svalbard.fr\/actualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4daa437093476dbc32da415c112b6512?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4daa437093476dbc32da415c112b6512?s=96&d=mm&r=g","caption":"Hilmar"},"description":"Hilmar est un passionn\u00e9 des r\u00e9gions polaires, sp\u00e9cialis\u00e9 dans la r\u00e9daction d'articles sur le Spitzberg et autres destinations arctiques. Il apporte son expertise et sa passion pour l'Arctique au sein de l'\u00e9quipe de r\u00e9daction de Svalbard depuis de nombreuses ann\u00e9es.","sameAs":["https:\/\/www.svalbard.fr\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.svalbard.fr\/actualites\/wp-json\/wp\/v2\/posts\/5665"}],"collection":[{"href":"https:\/\/www.svalbard.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.svalbard.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.svalbard.fr\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.svalbard.fr\/actualites\/wp-json\/wp\/v2\/comments?post=5665"}],"version-history":[{"count":1,"href":"https:\/\/www.svalbard.fr\/actualites\/wp-json\/wp\/v2\/posts\/5665\/revisions"}],"predecessor-version":[{"id":5667,"href":"https:\/\/www.svalbard.fr\/actualites\/wp-json\/wp\/v2\/posts\/5665\/revisions\/5667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.svalbard.fr\/actualites\/wp-json\/wp\/v2\/media\/5666"}],"wp:attachment":[{"href":"https:\/\/www.svalbard.fr\/actualites\/wp-json\/wp\/v2\/media?parent=5665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.svalbard.fr\/actualites\/wp-json\/wp\/v2\/categories?post=5665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.svalbard.fr\/actualites\/wp-json\/wp\/v2\/tags?post=5665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}